{"id":13054,"date":"2017-06-19T18:33:15","date_gmt":"2017-06-19T17:33:15","guid":{"rendered":"http:\/\/cen.pt\/blog\/?p=13054"},"modified":"2017-06-19T18:33:15","modified_gmt":"2017-06-19T17:33:15","slug":"cuidados-pele-masculina","status":"publish","type":"post","link":"https:\/\/www.cen.pt\/blog\/2017\/06\/19\/cuidados-pele-masculina\/","title":{"rendered":"Os cuidados com a pele masculina"},"content":{"rendered":"<p>A pele dos homens, tal como a das mulheres, necessita de cuidados espec\u00edficos para se manter saud\u00e1vel e com bom aspeto. Embora possa parecer mais resistente, porque tem de facto caracter\u00edsticas diferentes, a pele dos homens tem necessidades e sensibilidades espec\u00edficas que n\u00e3o devem ser descuradas.<\/p>\n<p>O que confere a estrutura ou composi\u00e7\u00e3o diferente \u00e0 pele masculina \u00e9 precisamente a Testosterona, a hormona masculina, respons\u00e1vel por um maior est\u00edmulo das gl\u00e2ndulas seb\u00e1ceas o que, logo \u00e0 partida, vai conferir uma maior oleosidade \u00e0 pele, mais espessura e diferentes comportamentos em termos de envelhecimento.<\/p>\n<p>Nesta sequ\u00eancia, pode dizer-se que a pele masculina \u00e9 cerca de 20% a 30% mais espessa do que a pele feminina, tendo a sua camada c\u00f3rnea perto de 20% mais de camadas. Al\u00e9m disso, ela cont\u00e9m mais colag\u00e9nio do que a pele feminina, com a vantagem de as suas fibras formarem uma esp\u00e9cie de rede (ao contr\u00e1rio do colag\u00e9nio na pele das mulheres, que se constitui em fibras paralelas), o que lhe d\u00e1 uma consist\u00eancia mais firme e el\u00e1stica. Conta ainda com a vantagem de ter uma maior capacidade para reter a \u00e1gua e ter mais vasos sangu\u00edneos, o que melhora o aporte de oxig\u00e9nio.<\/p>\n<p>Todas estas condi\u00e7\u00f5es levam a que o envelhecimento da pele masculina se d\u00ea de forma distinta do envelhecimento na pele feminina, ocorrendo normalmente mais tarde \u2013 no entanto, uma vez iniciado o processo, ele pode ser r\u00e1pido e os seus sinais bastante profundos. O facto de existir mais oleosidade e de os poros da pele masculina serem tamb\u00e9m maiores, vai por seu lado, induzir uma maior tend\u00eancia para acumula\u00e7\u00e3o de impurezas e surgimento da acne.<\/p>\n<p>No caso dos homens \u00e9 preciso n\u00e3o esquecer que, no que se refere \u00e0 pele do rosto especificamente, ela est\u00e1 sujeita a uma agress\u00e3o e <em>stress<\/em> constantes, em muitos casos di\u00e1ria: o barbear. Este ato de barbear vai remover a camada superior das c\u00e9lulas, o que torna a pele sens\u00edvel aos fatores externos. \u00c9 normal a pele barbeada desenvolver irrita\u00e7\u00e3o, vermelhid\u00e3o e descama\u00e7\u00e3o, porque o ato em si pode provocar microtraumas cut\u00e2neos, tornando a pele sens\u00edvel e vulner\u00e1vel \u00e0 a\u00e7\u00e3o das bact\u00e9rias, o que pode ser agravado com o uso de produtos de barbear ou p\u00f3s barba mais alcalinos e, logo, mais agressivos.<\/p>\n<p>Por isso se recomenda cuidado no barbear e o uso de produtos adequados ao tipo de pele de cada homem, com ingredientes antibacterianos e que proporcionem uma lubrifica\u00e7\u00e3o suficiente para ajudar as l\u00e2minas a deslizar suavemente sobre a pele. Al\u00e9m disso, o uso de l\u00e2minas limpas e bem afiadas, que n\u00e3o causem um atrito desnecess\u00e1rio na pele, \u00e9 muito importante. Fazer deslizar a l\u00e2mina no sentido do pelo, vai tamb\u00e9m ajudar a evitar esses atritos.<\/p>\n<p>Os produtos hidratantes ou anti envelhecimento para homem devem possuir uma textura ligeira e produtos oleosos devem ser sempre evitados, sobretudo quando usados na zona do rosto onde se situa a barba. O ideal \u00e9 optar por produtos em gel, gel creme ou fluidos (s\u00e9runs).<\/p>\n<p>E n\u00e3o se pense que por se usar a barba mais longa, como \u00e9 agora t\u00e3o comum, vai evitar os cuidados com a pele. \u00c9 verdade que os pelos do rosto poder\u00e3o proteger de algumas agress\u00f5es externas, como a exposi\u00e7\u00e3o ao sol ou a polui\u00e7\u00e3o, mas os cuidados do rosto continuam a ser necess\u00e1rios. Uma barba mal cuidada pode alterar o equil\u00edbrio do rosto e dificultar a limpeza adequada, pelo que se deve manter a higieniza\u00e7\u00e3o e hidrata\u00e7\u00e3o, de forma a manter a pele protegida e saud\u00e1vel.<\/p>\n<p>A <a href=\"https:\/\/pt.babor.com\/\">BABOR<\/a> disp\u00f5e de uma linha de produtos pensados especificamente para homem, com todos os ingredientes e texturas que eles mais necessitam e apreciam.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A pele dos homens, tal como a das mulheres, necessita de cuidados espec\u00edficos para se manter saud\u00e1vel e com bom aspeto. Embora possa parecer mais resistente, porque tem de facto caracter\u00edsticas diferentes, a pele dos homens tem necessidades e sensibilidades espec\u00edficas que n\u00e3o devem ser descuradas. O que confere a estrutura ou composi\u00e7\u00e3o diferente \u00e0&nbsp;<a href=\"https:\/\/www.cen.pt\/blog\/2017\/06\/19\/cuidados-pele-masculina\/\" class=\"read-more\">Continue Reading<\/a><\/p>\n","protected":false},"author":4,"featured_media":13055,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53,66],"tags":[283,164,282],"class_list":["post-13054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-as-nossas-sugestoes","category-babor","tag-cuidados-com-a-pele","tag-pele","tag-pele-masculina","cat-53-id","cat-66-id"],"_links":{"self":[{"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/posts\/13054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/comments?post=13054"}],"version-history":[{"count":0,"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/posts\/13054\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/media\/13055"}],"wp:attachment":[{"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/media?parent=13054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/categories?post=13054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/tags?post=13054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}