{"id":12982,"date":"2017-04-04T19:03:44","date_gmt":"2017-04-04T18:03:44","guid":{"rendered":"http:\/\/cen.pt\/blog\/?p=12982"},"modified":"2017-04-04T19:03:44","modified_gmt":"2017-04-04T18:03:44","slug":"biosseguranca-em-estetica","status":"publish","type":"post","link":"https:\/\/www.cen.pt\/blog\/2017\/04\/04\/biosseguranca-em-estetica\/","title":{"rendered":"Biosseguran\u00e7a em est\u00e9tica"},"content":{"rendered":"<p>A biosseguran\u00e7a, que tamb\u00e9m podemos chamar de higiene e seguran\u00e7a, compreende um conjunto de ac\u00e7\u00f5es que visam proteger os trabalhadores, minimizando os riscos inerentes \u00e0 sua atividade laboral, ao mesmo tempo que se protegem, no caso da est\u00e9tica, por exemplo, os clientes envolvidos nessa actividade.<\/p>\n<p>Quando vamos a um sal\u00e3o de beleza ou gabinete de est\u00e9tica, de alguma forma, vamos com o intuito de relaxar, usufruir de um servi\u00e7o que nos vai deixar mais satisfeitos com a nossa imagem e ambicionamos gozar de uns momentos de descontra\u00e7\u00e3o.<\/p>\n<p>Por isso devemos confiar as nossas m\u00e3os, os nossos p\u00e9s, o nosso cabelo, em suma: o nosso corpo, a profissionais que exer\u00e7am a sua actividade com conhecimento, profissionalismo e responsabilidade.<\/p>\n<p>Nestes espa\u00e7os, entra-se em contacto com pessoas que podem ser portadoras de doen\u00e7as contagiosas e que podem, por esse motivo,\u00a0 afetar tanto a sa\u00fade dos profissionais que a\u00ed trabalham como a de outros clientes.<\/p>\n<p>De acordo com a Constitui\u00e7\u00e3o da nossa Republica, todos t\u00eam o direito \u00e0 prote\u00e7\u00e3o da sa\u00fade e o dever de a defender e promover. Ao estado compete assegurar a presta\u00e7\u00e3o do trabalho em condi\u00e7\u00f5es de higiene e seguran\u00e7a, da\u00ed haver um controlo dos bens de consumo (cosm\u00e9ticos, produtos de higiene pessoal, etc) e da presta\u00e7\u00e3o de servi\u00e7os direta ou indiretamente relacionados com a sa\u00fade, como os servi\u00e7os nos institutos de beleza. \u00c0s entidades, de todos os ramos, compete organizar os servi\u00e7os de seguran\u00e7a e implementar as medidas necess\u00e1rias e obrigat\u00f3rias para a preven\u00e7\u00e3o dos riscos dos trabalhadores. Al\u00e9m disso, a entidade patronal deve tamb\u00e9m informar os seus trabalhadores sobre as medidas a aplicar na prote\u00e7\u00e3o da sua sa\u00fade e seguran\u00e7a e sobre a preven\u00e7\u00e3o de riscos no seu posto de trabalho, enquanto os pr\u00f3prios trabalhadores t\u00eam a obriga\u00e7\u00e3o de colaborar com a entidade patronal na concretiza\u00e7\u00e3o dessas medidas.<\/p>\n<p>No caso dos profissionais da \u00e1rea da est\u00e9tica e da beleza, eles devem fazer uso dos meios de prote\u00e7\u00e3o individual durante os procedimentos de manicura, pedicura, depila\u00e7\u00e3o, limpezas de pele, corte de cabelo, aplica\u00e7\u00e3o de produtos qu\u00edmicos e outros e devem proceder \u00e0 desinfe\u00e7\u00e3o de todos os instrumentos que utilizam nessas tarefas, recorrendo a produtos e procedimentos adequados. A utiliza\u00e7\u00e3o de luvas adequadas para evitar a exposi\u00e7\u00e3o cut\u00e2nea (precedida de uma boa higiene das m\u00e3os), a remo\u00e7\u00e3o de an\u00e9is ou adornos, antes de se proceder aos diversos trabalhos, \u00e9 de extrema import\u00e2ncia. Por isso, n\u00e3o devemos surpreender-nos nem olhar com desconfian\u00e7a um profissional que faz uso destes meios.<\/p>\n<p>Os procedimentos de limpeza e\/ou esteriliza\u00e7\u00e3o dos utens\u00edlios e instrumentos que entrem em contaco direto com os clientes s\u00e3o obrigat\u00f3rios. No caso dos t\u00eaxteis, estes devem ser lavados a uma temperatura superior a 90\u00ba. A limpeza e desinfe\u00e7\u00e3o do pr\u00f3prio ambiente de trabalho devem ser feitos diariamente. E al\u00e9m destes, outros procedimentos est\u00e3o a ser seguidos, mesmo quando n\u00f3s n\u00e3o estamos a olhar!<\/p>\n<p>\u00c9 preciso n\u00e3o esquecer que a preven\u00e7\u00e3o \u00e9 sempre o melhor tratamento.<\/p>\n<p>O cumprimento destes procedimentos, seja em pequenos espa\u00e7os de est\u00e9tica ou cabeleireiro, seja nos grandes sal\u00f5es ou institutos, servem n\u00e3o s\u00f3 para cumprir a lei, mas tamb\u00e9m para nos oferecer a n\u00f3s clientes a garantia de que a nossa sa\u00fade est\u00e1 protegida e cultivar aquele vinculo de confian\u00e7a que nos far\u00e1 voltar, porque sabemos que ali estamos seguros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A biosseguran\u00e7a, que tamb\u00e9m podemos chamar de higiene e seguran\u00e7a, compreende um conjunto de ac\u00e7\u00f5es que visam proteger os trabalhadores, minimizando os riscos inerentes \u00e0 sua atividade laboral, ao mesmo tempo que se protegem, no caso da est\u00e9tica, por exemplo, os clientes envolvidos nessa actividade. Quando vamos a um sal\u00e3o de beleza ou gabinete de&nbsp;<a href=\"https:\/\/www.cen.pt\/blog\/2017\/04\/04\/biosseguranca-em-estetica\/\" class=\"read-more\">Continue Reading<\/a><\/p>\n","protected":false},"author":4,"featured_media":12983,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[39],"tags":[230,232,61,231,233],"class_list":["post-12982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dicas-de-beleza","tag-biosseguranca","tag-desinfecao","tag-estetica","tag-higiene-e-seguranca","tag-procedimentos-de-seguranca","cat-39-id"],"_links":{"self":[{"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/posts\/12982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/comments?post=12982"}],"version-history":[{"count":0,"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/posts\/12982\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/media\/12983"}],"wp:attachment":[{"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/media?parent=12982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/categories?post=12982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/tags?post=12982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}