{"id":12502,"date":"2016-04-28T09:22:10","date_gmt":"2016-04-28T08:22:10","guid":{"rendered":"http:\/\/cen.pt\/blog\/?p=12502"},"modified":"2016-04-28T09:22:10","modified_gmt":"2016-04-28T08:22:10","slug":"drenagem-linfatica-manual","status":"publish","type":"post","link":"https:\/\/www.cen.pt\/blog\/2016\/04\/28\/drenagem-linfatica-manual\/","title":{"rendered":"Drenagem linf\u00e1tica manual"},"content":{"rendered":"<p>Porque os cuidados com o corpo, nos dias que correm, passaram a ser t\u00e3o importantes para o bem-estar f\u00edsico como emocional, algumas t\u00e9cnicas de massagem passaram a ter um maior destaque, como a Drenagem Linf\u00e1tica Manual.<\/p>\n<p>A Drenagem Linf\u00e1tica Manual \u00e9 uma t\u00e9cnica terap\u00eautica de massagem desenvolvida pelo m\u00e9dico dinamarqu\u00eas Emil Vodder em 1932.<\/p>\n<p>Tendo em considera\u00e7\u00e3o que o corpo humano \u00e9 constitu\u00eddo maioritariamente por \u00e1gua, \u00e9 a esse n\u00edvel que a Drenagem Linf\u00e1tica vai actuar, ajudando a eliminar o excesso de l\u00edquido e toxinas do corpo humano.<\/p>\n<p>Atrav\u00e9s da aplica\u00e7\u00e3o de movimentos suaves, precisos e ritmados, a esteticista vai estimular o funcionamento do sistema linf\u00e1tico, e ao mesmo tempo proporcionar uma sensa\u00e7\u00e3o de relaxamento e bem-estar \u00e0 sua cliente.<\/p>\n<p>Os principais objectivos da Drenagem Linf\u00e1tica Manual s\u00e3o:<\/p>\n<ul>\n<li>Estimular o sistema linf\u00e1tico;<\/li>\n<li>Diminuir transtornos circulat\u00f3rios como edema e linfedema;<\/li>\n<li>Auxiliar os tratamentos de combate \u00e0 celulite e gordura localizada;<\/li>\n<li>Auxiliar os processos de recupera\u00e7\u00e3o em cirurgias est\u00e9ticas ou qualquer outro p\u00f3s-operat\u00f3rio;<\/li>\n<li>Retardar o processo de envelhecimento cut\u00e2neo.<\/li>\n<\/ul>\n<p>Podemos ent\u00e3o concluir que \u00e9 uma t\u00e9cnica terap\u00eautica de massagem fundamental para o desenvolvimento e aperfei\u00e7oamento da futura Esteticista, assim como uma massagem indispens\u00e1vel para a manuten\u00e7\u00e3o do bem-estar f\u00edsico e emocional da futura cliente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Porque os cuidados com o corpo, nos dias que correm, passaram a ser t\u00e3o importantes para o bem-estar f\u00edsico como emocional, algumas t\u00e9cnicas de massagem passaram a ter um maior destaque, como a Drenagem Linf\u00e1tica Manual. A Drenagem Linf\u00e1tica Manual \u00e9 uma t\u00e9cnica terap\u00eautica de massagem desenvolvida pelo m\u00e9dico dinamarqu\u00eas Emil Vodder em 1932. Tendo&nbsp;<a href=\"https:\/\/www.cen.pt\/blog\/2016\/04\/28\/drenagem-linfatica-manual\/\" class=\"read-more\">Continue Reading<\/a><\/p>\n","protected":false},"author":4,"featured_media":12504,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[51,38],"tags":[59,61,87],"class_list":["post-12502","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-formacao-em-estetica","category-formacoes","tag-cen","tag-estetica","tag-massagem","post_format-post-format-image","cat-51-id","cat-38-id"],"_links":{"self":[{"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/posts\/12502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/comments?post=12502"}],"version-history":[{"count":0,"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/posts\/12502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/media\/12504"}],"wp:attachment":[{"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/media?parent=12502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/categories?post=12502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cen.pt\/blog\/wp-json\/wp\/v2\/tags?post=12502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}